{"id":7068,"date":"2013-09-06T10:58:30","date_gmt":"2013-09-06T10:58:30","guid":{"rendered":"http:\/\/destinocastillayleon.es\/index\/?p=7068"},"modified":"2014-10-27T11:32:00","modified_gmt":"2014-10-27T10:32:00","slug":"es-el-mes-del-queso-en-paradores","status":"publish","type":"post","link":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/","title":{"rendered":"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila"},"content":{"rendered":"<p><strong>Es el mes del queso en Paradores<\/strong> y en dos de los <strong><a title=\"Paradores con historia en Castilla y Le\u00f3n\" href=\"http:\/\/destinocastillayleon.es\/index\/paradores-con-historia-en-castilla-leon\/\" target=\"_blank\">paradores con m\u00e1s historia de Castilla y Le\u00f3n<\/a><\/strong> como son el Parador de \u00c1vila y el Parador de Gredos, se celebrar\u00e1n paralelamente las<strong> II Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena del\u00a06 al 15 de septiembre.<\/strong><br \/>\n&nbsp; <\/p>\n<h3><a title=\"Torta de la Serena, Extremadura\" href=\"http:\/\/www.tortaserena.com\/\" target=\"_blank\">La Torta de la Serena<\/a><\/h3>\n<p>Es un queso que se elabora con leche cruda de oveja merina y que se presenta de forma tradicional o en forma de torta, con una dura corteza exterior y una exquisita pasta de queso l\u00edquida, ideal para untar con pan. Para elaborar una torta de 1 kilo de utiliza leche proveniente de 15 ovejas merinas diferentes.<\/p>\n<p>Ser\u00e1 por la cercan\u00eda de \u00c1vila con Extremadura, que se utilicen quesos extreme\u00f1os, no tenemos nada en contra, pero quiz\u00e1 es que a\u00fan no han probado<strong> <a title=\"El Secreto de Armando, Quesos F\u00e9lix. Serrada\" href=\"http:\/\/destinocastillayleon.es\/index\/pasar-dia-en-serrada\/\" target=\"_blank\">\u00abEl Secreto de Armando\u00bb la torta de Quesos F\u00e9lix<\/a><\/strong> que se hace en Serrada (Valladolid).<br \/>\n&nbsp;<br \/>\n<center><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Secreto-de-Armando1-659x370.jpg\" alt=\"Queso el Secreto de armando\" title=\"Queso el Secreto de armando\" width=\"640\"\/><\/center><br \/>\n&nbsp;<br \/>\nIgualmente, es una oportunidad para conocer estos paradores y su maravilloso entorno. <strong>En el caso de \u00c1vila, este fin de semana se celebra su <a title=\"http:\/\/destinocastillayleon.es\/index\/ya-hay-programa-para-mercado-medieval-de-avila-2013\/\" href=\"http:\/\/destinocastillayleon.es\/index\/ya-hay-programa-para-mercado-medieval-de-avila-2013\/\" target=\"_blank\">Mercado Medieval<\/a>,<\/strong> y la naturaleza desbordante de rodea al Parador de \u00a0Gredos.<\/p>\n<p>En este \u00faltimo cuentan con <strong>propuestas gastron\u00f3micas elaboradas con Torta de la Seren<\/strong>a como ingrediente principal como:<\/p>\n<p>&nbsp;  &nbsp; &#8211; Ensalada templada de Pimientos asados con Torta de la Serena, Miel de \u2013 Ca\u00f1a y Cecina de Le\u00f3n Berenjenas rellenas de Setas y Gambas gratinada con Torta de la Serena<\/p>\n<p>&nbsp;  &nbsp; &#8211; Lomo de Lubina con Muselina de Torta de la Serena y Pisto Castellano<\/p>\n<p>&nbsp;  &nbsp; &#8211; Prensada de Cochinillo con Torta de la Serena y Salteado de Champi\u00f1\u00f3n<\/p>\n<p>&nbsp;  &nbsp; &#8211; Panacota de Torta de la Serena con Coul\u00eds de Frutos<\/p>\n<p><strong>Si est\u00e1s esos d\u00edas por all\u00ed, no te olvides de asistir a las II Jornadas Gastron\u00f3micas del Queso en Paradores. \u00a1\u00a1Te chupar\u00e1s los dedos!!<\/strong><\/p>\n<h4>Art\u00edculos relacionados:<\/h4>\n<p>&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/7-hitos-de-la-gastronomia-tipica-de-avila\/\" title=\"7 Hitos de la gastronmia t\u00edpica abulense\" target=\"_blank\"><span style=\"color: #000000;\">7 Hitos de la gastronmia t\u00edpica abulense<\/a>.<br \/>\n&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/siete-espacios-naturales-en-castilla-leon-para-disfrutar-del-buen-tiempo\/\" title=\"7 Parques naturales para disfrutar en Castilla y Le\u00f3n\" target=\"_blank\"><span style=\"color: #000000;\">7 Parques naturales para disfrutar en Castilla y Le\u00f3n<\/a>.<br \/>\n&nbsp; &nbsp; <strong>\u2022 <\/strong><a title=\"Enlace a nuestra entrada sobre nuestra visita a Aguilar de Campoo\" href=\"http:\/\/destinocastillayleon.es\/index\/conclusiones-del-estudio-y-ti-como-te-gustan-los-quesos\/\" target=\"_blank\"><span style=\"color: #000000;\">Conclusiones del estudio sobre qu\u00e9 tipo de queso gusta a nuestros lectores<\/a>.<br \/>\n&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena<\/p>\n","protected":false},"author":6,"featured_media":7069,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_1150954226_1150954226":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[77,62,68],"tags":[2349,64,843,3625,2348,1649],"class_list":["post-7068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-agenda-de-castilla-y-leon","category-avila","category-post_inicial","tag-activades-en-el-parador-nacional-de-gredos","tag-avila-2","tag-ii-jornadas-gastronomicas-del-queso-en-paradores","tag-mes-del-queso-en-el-parador-nacional-de-gredos","tag-parador-nacional-de-gredos","tag-quesos-de-castilla-y-leon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mes del Queso en el Parador Nacional de Gredos, \u00c1vila - Destino Castilla y Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena\" \/>\n<meta property=\"og:url\" content=\"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/\" \/>\n<meta property=\"og:site_name\" content=\"Destino Castilla y Le\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DestinoCastillaYLeon\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-06T10:58:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-27T10:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Quesos-de-la-Serena-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"611\" \/>\n\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola Hernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@destinocyl\" \/>\n<meta name=\"twitter:site\" content=\"@destinocyl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola Hernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/\"},\"author\":{\"name\":\"Lola Hernandez\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/49ffcb7eb307589ba529009335ed7767\"},\"headline\":\"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila\",\"datePublished\":\"2013-09-06T10:58:30+00:00\",\"dateModified\":\"2014-10-27T10:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/\"},\"wordCount\":378,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Quesos-de-la-Serena-1.jpg\",\"keywords\":[\"Activades en el Parador Nacional de Gredos\",\"avila\",\"II Jornadas Gastron\u00f3micas del Queso en Paradores\",\"Mes del Queso en el Parador Nacional de Gredos\",\"Parador Nacional de Gredos\",\"Quesos de Castilla y Le\u00f3n\"],\"articleSection\":[\"Actualidad\",\"Avila\",\"Post_inicial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/\",\"name\":\"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila - Destino Castilla y Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Quesos-de-la-Serena-1.jpg\",\"datePublished\":\"2013-09-06T10:58:30+00:00\",\"dateModified\":\"2014-10-27T10:32:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/49ffcb7eb307589ba529009335ed7767\"},\"description\":\"Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Quesos-de-la-Serena-1.jpg\",\"contentUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Quesos-de-la-Serena-1.jpg\",\"width\":611,\"height\":382},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/es-el-mes-del-queso-en-paradores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#website\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/\",\"name\":\"Destino Castilla y Le\u00f3n\",\"description\":\"Medio digital independiente y revista de Castilla y Le\u00f3n dedicado al turismo, gastronom\u00eda y vino de Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/49ffcb7eb307589ba529009335ed7767\",\"name\":\"Lola Hernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g\",\"caption\":\"Lola Hernandez\"},\"description\":\"Lola Hern\u00e1ndez fue fundadora y directora de www.destinocastillayleon.es Escribiendo sobre turismo, gastronom\u00eda y vino de su tierra de origen, Castilla y Le\u00f3n.\",\"sameAs\":[\"http:\\\/\\\/www.destinoysabor.com\\\/blog\"],\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/author\\\/lola-hernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila - Destino Castilla y Le\u00f3n","description":"Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/","og_locale":"es_ES","og_type":"article","og_title":"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila","og_description":"Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena","og_url":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/","og_site_name":"Destino Castilla y Le\u00f3n","article_publisher":"https:\/\/www.facebook.com\/DestinoCastillaYLeon\/","article_published_time":"2013-09-06T10:58:30+00:00","article_modified_time":"2014-10-27T10:32:00+00:00","og_image":[{"width":611,"height":382,"url":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Quesos-de-la-Serena-1.jpg","type":"image\/jpeg"}],"author":"Lola Hernandez","twitter_card":"summary_large_image","twitter_creator":"@destinocyl","twitter_site":"@destinocyl","twitter_misc":{"Escrito por":"Lola Hernandez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#article","isPartOf":{"@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/"},"author":{"name":"Lola Hernandez","@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/49ffcb7eb307589ba529009335ed7767"},"headline":"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila","datePublished":"2013-09-06T10:58:30+00:00","dateModified":"2014-10-27T10:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/"},"wordCount":378,"commentCount":0,"image":{"@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#primaryimage"},"thumbnailUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Quesos-de-la-Serena-1.jpg","keywords":["Activades en el Parador Nacional de Gredos","avila","II Jornadas Gastron\u00f3micas del Queso en Paradores","Mes del Queso en el Parador Nacional de Gredos","Parador Nacional de Gredos","Quesos de Castilla y Le\u00f3n"],"articleSection":["Actualidad","Avila","Post_inicial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/","url":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/","name":"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila - Destino Castilla y Le\u00f3n","isPartOf":{"@id":"https:\/\/destinocastillayleon.es\/index\/#website"},"primaryImageOfPage":{"@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#primaryimage"},"image":{"@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#primaryimage"},"thumbnailUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Quesos-de-la-Serena-1.jpg","datePublished":"2013-09-06T10:58:30+00:00","dateModified":"2014-10-27T10:32:00+00:00","author":{"@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/49ffcb7eb307589ba529009335ed7767"},"description":"Acompa\u00f1anos en las Jornadas del Mes del Queso en el Parador Nacional y de la Torta de la Serena","breadcrumb":{"@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#primaryimage","url":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Quesos-de-la-Serena-1.jpg","contentUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2013\/09\/Quesos-de-la-Serena-1.jpg","width":611,"height":382},{"@type":"BreadcrumbList","@id":"https:\/\/destinocastillayleon.es\/index\/es-el-mes-del-queso-en-paradores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/destinocastillayleon.es\/index\/"},{"@type":"ListItem","position":2,"name":"Mes del Queso en el Parador Nacional de Gredos, \u00c1vila"}]},{"@type":"WebSite","@id":"https:\/\/destinocastillayleon.es\/index\/#website","url":"https:\/\/destinocastillayleon.es\/index\/","name":"Destino Castilla y Le\u00f3n","description":"Medio digital independiente y revista de Castilla y Le\u00f3n dedicado al turismo, gastronom\u00eda y vino de Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/destinocastillayleon.es\/index\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/49ffcb7eb307589ba529009335ed7767","name":"Lola Hernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g","caption":"Lola Hernandez"},"description":"Lola Hern\u00e1ndez fue fundadora y directora de www.destinocastillayleon.es Escribiendo sobre turismo, gastronom\u00eda y vino de su tierra de origen, Castilla y Le\u00f3n.","sameAs":["http:\/\/www.destinoysabor.com\/blog"],"url":"https:\/\/destinocastillayleon.es\/index\/author\/lola-hernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/7068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/comments?post=7068"}],"version-history":[{"count":11,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/7068\/revisions"}],"predecessor-version":[{"id":16585,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/7068\/revisions\/16585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/media\/7069"}],"wp:attachment":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/media?parent=7068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/categories?post=7068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/tags?post=7068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}