{"id":24133,"date":"2017-01-04T08:46:10","date_gmt":"2017-01-04T07:46:10","guid":{"rendered":"http:\/\/destinocastillayleon.es\/index\/?p=24133"},"modified":"2018-04-12T07:55:08","modified_gmt":"2018-04-12T05:55:08","slug":"guia-para-visitar-segovia","status":"publish","type":"post","link":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/","title":{"rendered":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otro puntos de interesantes"},"content":{"rendered":"<p>Con esta entrega, finalizamos esta <strong>gu\u00eda para conocer Segovia<\/strong>, una ciudad m\u00e1gica llena de lugares encantados y que os hemos ido desglosando, desde las piedras milenarias que forman parte del <a href=\"http:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia-ciudad-vieja-y-su-acueducto\/\">Acueducto<\/a> o del <a href=\"http:\/\/destinocastillayleon.es\/index\/alcazar-de-segovia-2\/\">Alc\u00e1zar<\/a>; Tambi\u00e9n hemos conocido <a href=\"http:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia-la-catedral-de-segovia\/\">los secretos de la Catedral<\/a>; y en esta ocasi\u00f3n, <strong>vamos a conocer un poco m\u00e1s a fondo las murallas de la ciudad y otros monumentos interesantes de Segovia<\/strong>.<br \/>\n&nbsp; <\/p>\n<h2>Gu\u00eda para visitar Segovia: Las Murallas de Segovia<\/h2>\n<p><strong>El origen de las murallas se pierden en el tiempo<\/strong>; Ya exist\u00edan cuando Alfonso VI de Castilla arrebat\u00f3 la ciudad a los \u00e1rabes. En seguida mand\u00f3 su ampliaci\u00f3n, llegando a tener un per\u00edmetro de 3 kil\u00f3metros, 80 torres, 5 puertas y varios portillos. <\/p>\n<p>Su construcci\u00f3n se realiz\u00f3 usando sillares de granito, aunque tambi\u00e9n se reutilizaron  l\u00e1pidas  de la necr\u00f3polis romana. La muralla recorre el casco antiguo, y en la actualidad a\u00fan conserva tres puertas: San Cebri\u00e1n, Santiago, de aspecto mud\u00e9jar; y San Andr\u00e9s, puerta de acceso a la juder\u00eda, y los portillos del Consuelo, de San Juan, del Sol y de la Luna. <\/p>\n<p><figure id=\"attachment_17787\" aria-describedby=\"caption-attachment-17787\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2015\/01\/c41d563636337c9dd29e3367ffdfc6e8.jpg\" alt=\"Destino Castilla y Le\u00f3n - Murallas de Segovia\" width=\"680\" height=\"369\" class=\"size-full wp-image-17787\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2015\/01\/c41d563636337c9dd29e3367ffdfc6e8.jpg 680w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2015\/01\/c41d563636337c9dd29e3367ffdfc6e8-300x162.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption id=\"caption-attachment-17787\" class=\"wp-caption-text\">Destino Castilla y Le\u00f3n &#8211; Murallas de Segovia<\/figcaption><\/figure><br \/>\n&nbsp; <\/p>\n<h2>Otras construcciones rom\u00e1nicas en Segovia<\/h2>\n<h3>La ciudad conserva un importante conjunto de iglesias rom\u00e1nicas<\/h3>\n<p>Tanto de piedra como de ladrillo, donde destacan <strong>San Esteban y San Mill\u00e1n<\/strong>, situado junto a la avenida Fern\u00e1ndez Ladreda, en el barrio de San Mill\u00e1n de Segovia, o <strong>San Mart\u00edn<\/strong>, en los intramuros de la ciudad la Sant\u00edsima Trinidad.<\/p>\n<p><a href=\"http:\/\/yotuguiaturismo.com\/que-ver-y-visitar-en-segovia-lugares-interesantes\/\" target=\"_blank\"><figure id=\"attachment_24145\" aria-describedby=\"caption-attachment-24145\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/82799ffbccb8160f13972f779dc8ae95.jpg\" alt=\"Gu\u00eda para visitar Segovia\" title=\"Iglesia de San Mart\u00edn de Segovia - imagen de YotuGu\u00edadeturismo\" width=\"640\" height=\"460\" class=\"size-full wp-image-24145\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/82799ffbccb8160f13972f779dc8ae95.jpg 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/82799ffbccb8160f13972f779dc8ae95-300x216.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-24145\" class=\"wp-caption-text\">Iglesia de San Mart\u00edn de Segovia<\/figcaption><\/figure><\/a><\/p>\n<p>El actual templo obra del siglo XII sucedi\u00f3 a otro m\u00e1s primitivo de finales del siglo XI, San Andr\u00e9s, San Clemente, Santos Justo y Pastor, la iglesia de la Vera Cruz anteriormente titulada como Santo Sepulcro, es un templo cat\u00f3lico situado en el barrio de San Marcos de la ciudad de Segovia y San Salvador entre otras. <\/p>\n<p>Tambi\u00e9n en Segovia <strong>se conservan diversos conventos y monasterios, como el de Santa Mar\u00eda del Parral<\/strong>, que es un convento de clausura mon\u00e1stica ubicado en la ciudad de Segovia; O <strong>tambi\u00e9n el Monasterio de San Vicente el Real<\/strong>, que est\u00e1 situado extramuros de la ciudad de Segovia.<\/p>\n<p><figure id=\"attachment_16208\" aria-describedby=\"caption-attachment-16208\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/Monasterio-del-Parral-Segovia2.jpg\" alt=\"Monasterio del Parral Segovia\" width=\"640\" height=\"428\" class=\"size-full wp-image-16208\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/Monasterio-del-Parral-Segovia2.jpg 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/Monasterio-del-Parral-Segovia2-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-16208\" class=\"wp-caption-text\">Monasterio del Parral Segovia<\/figcaption><\/figure><br \/>\n&nbsp; <\/p>\n<h3>Otros monumentos importantes <\/h3>\n<h4>El palacete de Ayala Berganza<\/h4>\n<p><strong>El palacete de estilo castellano Ayala Berganza<\/strong> est\u00e1 construido a finales del siglo XV, declarado Monumento Hist\u00f3rico-Art\u00edstico, convertido actualmente en alojamiento tur\u00edstico, en la calle Carretas. <\/p>\n<blockquote><p>Debido a un asesinato m\u00faltiple sucedido a finales del siglo XIX es conocido por los segovianos como la casa del crimen.<\/p><\/blockquote>\n<p><a href=http:\/\/www.unaventanadesdemadrid.com\/otras-comunidades\/segovia-v.html target=\"_blank\"><figure id=\"attachment_24150\" aria-describedby=\"caption-attachment-24150\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/Palacio-de-Los-Ayala-Berganza-Imagen-de-UnaAventuradesdeMadrid.jpg\" alt=\"Palacio de Los Ayala Berganza - Imagen de UnaAventuradesdeMadrid\" width=\"640\" height=\"430\" class=\"size-full wp-image-24150\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/Palacio-de-Los-Ayala-Berganza-Imagen-de-UnaAventuradesdeMadrid.jpg 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/Palacio-de-Los-Ayala-Berganza-Imagen-de-UnaAventuradesdeMadrid-300x202.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-24150\" class=\"wp-caption-text\">Palacio de Los Ayala Berganza<\/figcaption><\/figure><\/a><br \/>\n&nbsp; <\/p>\n<h4>M\u00e1s casonas solariegas<\/h4>\n<p>Segovia a\u00fan conserva <strong>abundantes palacios medievales con fachadas, portadas, patios de columnas, escudos y torreones<\/strong>. Se pueden destacar diversas portadas <strong>en la calle Dao\u00edz<\/strong>, la Casa del Sello en la calle San Francisco, <strong>la Casa-Museo del Torre\u00f3n de Lozoya<\/strong> en la plaza de San Mart\u00edn, <strong>la Casa del Siglo XV o de Juan Bravo<\/strong>, la <strong>Casa de los Picos<\/strong>, construido por Pedro L\u00f3pez de Ayala, la <strong>Casa del Conde Alpuente<\/strong>  y otras de la Calle Real.<\/p>\n<p><a href=\"http:\/\/www.viajesconmiperro.com\/2015\/04\/la-casona-de-espirdo-espirdo-segovia.html\" target=\"_blank\"><figure id=\"attachment_24148\" aria-describedby=\"caption-attachment-24148\" style=\"width: 403px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6e6f1dd223c00c57eaaed62cfc24abdb.jpg\" alt=\"Gu\u00eda para visitar Segovia\" title=\"Cas\u00f3n del Conde Alpuente - Imagen de ViajesconmiPerro\" width=\"403\" height=\"564\" class=\"size-full wp-image-24148\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6e6f1dd223c00c57eaaed62cfc24abdb.jpg 379w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6e6f1dd223c00c57eaaed62cfc24abdb-214x300.jpg 214w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6e6f1dd223c00c57eaaed62cfc24abdb-300x420.jpg 300w\" sizes=\"(max-width: 403px) 100vw, 403px\" \/><figcaption id=\"caption-attachment-24148\" class=\"wp-caption-text\">Cas\u00f3n del Conde Alpuente &#8211; Imagen de ViajesconmiPerro<\/figcaption><\/figure><\/a><br \/>\n&nbsp; <\/p>\n<h4>La taberna en activo m\u00e1s antigua de la ciudad y otras de inter\u00e9s<\/h4>\n<p>Todav\u00eda se puede disfrutar de <strong>la taberna m\u00e1s antigua de la ciudad<\/strong>, que data de 1861. Se trata de la Taberna Rubi, situada a pocos pasos del Ayuntamiento de Segovia y de la Catedral de Segovia. <\/p>\n<p><a href=\"http:\/\/tapeanding.com\/ciudades\/tapas-gratis-en-segovia\/tapas-gratis-en-segovia-capital\/\" target=\"_blank\"><figure id=\"attachment_24147\" aria-describedby=\"caption-attachment-24147\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6bb4de840dbdaff8c35d3c92f31afdbf.jpg\" alt=\"Gu\u00eda para visitar Segovia\" title=\"Taberna Rub\u00ed de Segovia - Imagen de Tapeanding\" width=\"640\" height=\"460\" class=\"size-full wp-image-24147\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6bb4de840dbdaff8c35d3c92f31afdbf.jpg 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/6bb4de840dbdaff8c35d3c92f31afdbf-300x216.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-24147\" class=\"wp-caption-text\">Taberna Rub\u00ed de Segovia &#8211; Imagen de Tapeanding<\/figcaption><\/figure><\/a><\/p>\n<p>Bajando por este callej\u00f3n podemos encontrarnos con <strong>la casa de Antonio Machado<\/strong>, y si seguimos caminando llegaremos finalmente a la plaza del Alc\u00e1zar de Segovia, donde adem\u00e1s est\u00e1 la escuela militar de artiller\u00eda. <\/p>\n<figure id=\"attachment_16212\" aria-describedby=\"caption-attachment-16212\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/Casa-Museo-de-Antonio-Machado-en-Segovia.jpg\" alt=\"Gu\u00eda para visitar Segovia\" title=\"Casa Museo de Antonio Machado en Segovia\" width=\"640\" height=\"428\" class=\"size-full wp-image-16212\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/Casa-Museo-de-Antonio-Machado-en-Segovia.jpg 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/Casa-Museo-de-Antonio-Machado-en-Segovia-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-16212\" class=\"wp-caption-text\">Casa Museo de Antonio Machado en Segovia<\/figcaption><\/figure>\n<p>Si bajamos hacia la ribera del r\u00edo Eresma, que antes de llegar a la ciudad se le conoce como Valsa\u00edn, encontrar\u00e9is <strong>La Casa de la Moneda<\/strong>, el edificio industrial m\u00e1s antiguo de Europa, que tras una reciente rehabilitaci\u00f3n en 2011, <strong>est\u00e1 abierta como museo y como cafeter\u00eda con terraza con vistas al r\u00edo<\/strong>. Adem\u00e1s posee una preciosa vista del Alc\u00e1zar.<\/p>\n<p><figure id=\"attachment_16205\" aria-describedby=\"caption-attachment-16205\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/37b2e59b1320188b56873e4f4728f3ce.jpg\" alt=\"La Real F\u00e1brica de la Moneda de Segovia\" width=\"640\" height=\"428\" class=\"size-full wp-image-16205\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/37b2e59b1320188b56873e4f4728f3ce.jpg 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/10\/37b2e59b1320188b56873e4f4728f3ce-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-16205\" class=\"wp-caption-text\">La Real F\u00e1brica de la Moneda de Segovia<\/figcaption><\/figure><br \/>\n&nbsp; <\/p>\n<h5>Nota<\/h5>\n<p>Portada de la entrada cortes\u00eda de<a href=\"http:\/\/www.eldiario.es\/\" target=\"_blank\"> El Diario<\/a>.<br \/>\n&nbsp; <\/p>\n<h4>Tambi\u00e9n te puede interesar<\/h4>\n<ul>\n<li><a href=\"http:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia-ciudad-vieja-y-su-acueducto\/\">Gu\u00eda para visitar Segovia (Parte I) Ciudad vieja y su acueducto<\/a>.<\/li>\n<li><a href=\"http:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia-la-catedral-de-segovia\/\">Gu\u00eda para visitar Segovia (Parte II) La catedral de Segovia<\/a>.<\/li>\n<li><a href=\"http:\/\/destinocastillayleon.es\/index\/rincones-secretos-de-segovia\/\">10 rincones secretos de Segovia<\/a>.<\/li>\n<li><a href=\"http:\/\/destinocastillayleon.es\/index\/ruta-de-los-castillos-de-segovia\/\">Recorre la Ruta de los Castillos de Segovia y su provincia<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia<\/p>\n","protected":false},"author":21,"featured_media":24146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_1150954226_1150954226":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[68,45,73,384,37,4738],"tags":[769,5105,5098,3521,369,564,3281],"class_list":["post-24133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-post_inicial","category-provincias","category-punto_singular","category-rutas-2","category-segovia","category-segovia-turismo","tag-destino-castilla-y-leon","tag-guia-de-segovia","tag-monumentos-interesantes-de-segovia","tag-planes-en-segovia","tag-turismo-en-castilla-y-leon","tag-turismo-en-segovia","tag-visitar-segovia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros interesantes<\/title>\n<meta name=\"description\" content=\"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros puntos de interesantes para descubrir\" \/>\n<meta property=\"og:description\" content=\"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/\" \/>\n<meta property=\"og:site_name\" content=\"Destino Castilla y Le\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DestinoCastillaYLeon\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/narciso.casas?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-04T07:46:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-12T05:55:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Narciso Casas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros puntos de interesantes para descubrir\" \/>\n<meta name=\"twitter:description\" content=\"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064-300x300.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/narcisocasas\" \/>\n<meta name=\"twitter:site\" content=\"@destinocyl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Narciso Casas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/\"},\"author\":{\"name\":\"Narciso Casas\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/1becc9e19ead9f0fc2021be0bbc80ea7\"},\"headline\":\"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otro puntos de interesantes\",\"datePublished\":\"2017-01-04T07:46:10+00:00\",\"dateModified\":\"2018-04-12T05:55:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/\"},\"wordCount\":854,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/ab2c698a1992949238f680ddf3166064.jpg\",\"keywords\":[\"Destino Castilla y Le\u00f3n\",\"gu\u00eda de segovia\",\"monumentos interesantes de Segovia\",\"planes en segovia\",\"turismo en Castilla y Le\u00f3n\",\"turismo en Segovia\",\"visitar Segovia\"],\"articleSection\":[\"Post_inicial\",\"Provincias\",\"Punto Singular\",\"Rutas\",\"Segovia\",\"Segovia turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/\",\"name\":\"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros interesantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/ab2c698a1992949238f680ddf3166064.jpg\",\"datePublished\":\"2017-01-04T07:46:10+00:00\",\"dateModified\":\"2018-04-12T05:55:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/1becc9e19ead9f0fc2021be0bbc80ea7\"},\"description\":\"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/ab2c698a1992949238f680ddf3166064.jpg\",\"contentUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/ab2c698a1992949238f680ddf3166064.jpg\",\"width\":800,\"height\":531,\"caption\":\"Portada de la gu\u00eda de Segovia III - Imagen de Gu\u00eda de Urgencia para fin de semana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/guia-para-visitar-segovia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otro puntos de interesantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#website\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/\",\"name\":\"Destino Castilla y Le\u00f3n\",\"description\":\"Medio digital independiente y revista de Castilla y Le\u00f3n dedicado al turismo, gastronom\u00eda y vino de Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/1becc9e19ead9f0fc2021be0bbc80ea7\",\"name\":\"Narciso Casas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/091e8d37626e66ff26a9f756f698c44cd4f2f8d54dcdb29458075251b4ba3dc5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/091e8d37626e66ff26a9f756f698c44cd4f2f8d54dcdb29458075251b4ba3dc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/091e8d37626e66ff26a9f756f698c44cd4f2f8d54dcdb29458075251b4ba3dc5?s=96&d=mm&r=g\",\"caption\":\"Narciso Casas\"},\"description\":\"Desde Madrid, formado en Bellas Artes, Restauraci\u00f3n y Conservaci\u00f3n de obras de arte. Gracias a esta capacitaci\u00f3n ha realizado exposiciones por diversos pa\u00edses. Adem\u00e1s, es licenciado en publicidad y marketing por la Universidad Deusto. Tambi\u00e9n posee varios masters. Colabora con la revista digital Historia y Arqueolog\u00eda y ha publicado varios libros que puedes adquirir aqu\u00ed: http:\\\/\\\/librosdenarcisocasas.blogspot.com.es\\\/\",\"sameAs\":[\"http:\\\/\\\/librosdenarcisocasas.blogspot.com.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/narciso.casas?ref=br_rs\",\"https:\\\/\\\/www.instagram.com\\\/casasnarciso\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/narciso-casas-6b592a48\",\"https:\\\/\\\/es.pinterest.com\\\/narciso_c\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/narcisocasas\"],\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/author\\\/narciso-casas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros interesantes","description":"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/","og_locale":"es_ES","og_type":"article","og_title":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros puntos de interesantes para descubrir","og_description":"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia","og_url":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/","og_site_name":"Destino Castilla y Le\u00f3n","article_publisher":"https:\/\/www.facebook.com\/DestinoCastillaYLeon\/","article_author":"https:\/\/www.facebook.com\/narciso.casas?ref=br_rs","article_published_time":"2017-01-04T07:46:10+00:00","article_modified_time":"2018-04-12T05:55:08+00:00","og_image":[{"width":800,"height":531,"url":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064.jpg","type":"image\/jpeg"}],"author":"Narciso Casas","twitter_card":"summary_large_image","twitter_title":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros puntos de interesantes para descubrir","twitter_description":"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia","twitter_image":"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064-300x300.jpg","twitter_creator":"@https:\/\/twitter.com\/narcisocasas","twitter_site":"@destinocyl","twitter_misc":{"Escrito por":"Narciso Casas","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#article","isPartOf":{"@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/"},"author":{"name":"Narciso Casas","@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/1becc9e19ead9f0fc2021be0bbc80ea7"},"headline":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otro puntos de interesantes","datePublished":"2017-01-04T07:46:10+00:00","dateModified":"2018-04-12T05:55:08+00:00","mainEntityOfPage":{"@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/"},"wordCount":854,"commentCount":1,"image":{"@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#primaryimage"},"thumbnailUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064.jpg","keywords":["Destino Castilla y Le\u00f3n","gu\u00eda de segovia","monumentos interesantes de Segovia","planes en segovia","turismo en Castilla y Le\u00f3n","turismo en Segovia","visitar Segovia"],"articleSection":["Post_inicial","Provincias","Punto Singular","Rutas","Segovia","Segovia turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/","url":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/","name":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otros interesantes","isPartOf":{"@id":"https:\/\/destinocastillayleon.es\/index\/#website"},"primaryImageOfPage":{"@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#primaryimage"},"image":{"@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#primaryimage"},"thumbnailUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064.jpg","datePublished":"2017-01-04T07:46:10+00:00","dateModified":"2018-04-12T05:55:08+00:00","author":{"@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/1becc9e19ead9f0fc2021be0bbc80ea7"},"description":"Gu\u00eda para visitar Segovia, tercera entrega. Conoce con detalle algunos de los puntos m\u00e1s interesantes que recorrer en una visita a la maravillosa Segovia","breadcrumb":{"@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#primaryimage","url":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064.jpg","contentUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2016\/12\/ab2c698a1992949238f680ddf3166064.jpg","width":800,"height":531,"caption":"Portada de la gu\u00eda de Segovia III - Imagen de Gu\u00eda de Urgencia para fin de semana"},{"@type":"BreadcrumbList","@id":"https:\/\/destinocastillayleon.es\/index\/guia-para-visitar-segovia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/destinocastillayleon.es\/index\/"},{"@type":"ListItem","position":2,"name":"Gu\u00eda para visitar Segovia (Parte III) Las murallas y otro puntos de interesantes"}]},{"@type":"WebSite","@id":"https:\/\/destinocastillayleon.es\/index\/#website","url":"https:\/\/destinocastillayleon.es\/index\/","name":"Destino Castilla y Le\u00f3n","description":"Medio digital independiente y revista de Castilla y Le\u00f3n dedicado al turismo, gastronom\u00eda y vino de Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/destinocastillayleon.es\/index\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/1becc9e19ead9f0fc2021be0bbc80ea7","name":"Narciso Casas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/091e8d37626e66ff26a9f756f698c44cd4f2f8d54dcdb29458075251b4ba3dc5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/091e8d37626e66ff26a9f756f698c44cd4f2f8d54dcdb29458075251b4ba3dc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/091e8d37626e66ff26a9f756f698c44cd4f2f8d54dcdb29458075251b4ba3dc5?s=96&d=mm&r=g","caption":"Narciso Casas"},"description":"Desde Madrid, formado en Bellas Artes, Restauraci\u00f3n y Conservaci\u00f3n de obras de arte. Gracias a esta capacitaci\u00f3n ha realizado exposiciones por diversos pa\u00edses. Adem\u00e1s, es licenciado en publicidad y marketing por la Universidad Deusto. Tambi\u00e9n posee varios masters. Colabora con la revista digital Historia y Arqueolog\u00eda y ha publicado varios libros que puedes adquirir aqu\u00ed: http:\/\/librosdenarcisocasas.blogspot.com.es\/","sameAs":["http:\/\/librosdenarcisocasas.blogspot.com.es\/","https:\/\/www.facebook.com\/narciso.casas?ref=br_rs","https:\/\/www.instagram.com\/casasnarciso\/","https:\/\/www.linkedin.com\/in\/narciso-casas-6b592a48","https:\/\/es.pinterest.com\/narciso_c\/","https:\/\/x.com\/https:\/\/twitter.com\/narcisocasas"],"url":"https:\/\/destinocastillayleon.es\/index\/author\/narciso-casas\/"}]}},"_links":{"self":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/24133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/comments?post=24133"}],"version-history":[{"count":14,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/24133\/revisions"}],"predecessor-version":[{"id":24255,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/24133\/revisions\/24255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/media\/24146"}],"wp:attachment":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/media?parent=24133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/categories?post=24133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/tags?post=24133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}