{"id":12373,"date":"2014-03-29T17:37:35","date_gmt":"2014-03-29T17:37:35","guid":{"rendered":"http:\/\/destinocastillayleon.es\/index\/?p=12373"},"modified":"2014-11-21T11:24:35","modified_gmt":"2014-11-21T10:24:35","slug":"la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo","status":"publish","type":"post","link":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/","title":{"rendered":"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo"},"content":{"rendered":"<p style=\"text-align: justify;\">Por fin hemos sabido la fecha en la que<strong> \u00abEucharistia\u00bb, <\/strong>la muestra m\u00e1s destacada de arte sacro a nivel nacional e internacional, tendr\u00e1 lugar en Aranda de Duero, Burgos.<strong> Ser\u00e1 el 6 de mayo con la presencia de La Infanta Do\u00f1a Elena<\/strong> de Borb\u00f3n y Grecia.<\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.5em;\">Ya queda poco para que se inaugure \u2018Eucharistia\u2019, el pistoletazo de salida a 5 meses en los que Aranda de Duero recibir\u00e1 con los brazos abiertos a los miles de viajeros que viajar\u00e1n hasta la villa burgalesa para <strong>disfrutar de las Edades del hombr<\/strong>e as\u00ed como de las visitas teatralizadas,<strong> el video mapping<\/strong> de la iglesia de Santa Mar\u00eda y el <strong>mercado tem\u00e1tico<\/strong> que estar\u00e1 durante los d\u00edas en los que dure la exposici\u00f3n\u201d.\u00a0<\/span><\/p>\n<p>&nbsp; <\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/Fachada-Iglesia-Santa-Maria-Aranda-de-Duero-Burgos.png\"><img decoding=\"async\" class=\"size-full wp-image-12381 aligncenter\" title=\"Fachada Iglesia Santa Maria Aranda de Duero Burgos\" alt=\"Fachada Iglesia Santa Maria Aranda de Duero Burgos\" src=\"http:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/Fachada-Iglesia-Santa-Maria-Aranda-de-Duero-Burgos.png\" width=\"640\" height=\"415\" srcset=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/Fachada-Iglesia-Santa-Maria-Aranda-de-Duero-Burgos.png 640w, https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/Fachada-Iglesia-Santa-Maria-Aranda-de-Duero-Burgos-300x194.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp; <\/p>\n<p style=\"text-align: justify;\">Bajo el lema \u2018Eucharistia\u2019, la exposici\u00f3n estar\u00e1 dividida<strong> en cuatro cap\u00edtulos y contar\u00e1 con cerca de 130 piezas de arte sacro<\/strong> tra\u00eddas de diferentes di\u00f3cesis, que representan la riqueza religiosa incalculable de Castilla y Le\u00f3n y que ser\u00e1n expuestas en dos iglesias: <strong>las iglesias de Santa Mar\u00eda y San Juan.<\/strong><\/p>\n<p style=\"text-align: justify;\">Hasta su inauguraci\u00f3n,<strong> la localidad ribere\u00f1a continuar\u00e1 perfilando y ultimando\u00a0<\/strong>los detalles para lograr que esta nueva edici\u00f3n de las Edades del Hombre sea todo un \u00e9xito. Si te animas a visitar \u00abEucharistia\u00bb ver\u00e1s tambi\u00e9n nuevos establecimientos en las proximidades de la Iglesia de Santa Mar\u00eda donde se ofrecer\u00e1n productos de la zona, delicatessen y gourmet. Incluso una <strong>Tienda de los Aromas,<\/strong> tra\u00eddos del propio <a title=\"Museo de los Aromas\" href=\"http:\/\/www.museodelosaromas.com\/index.php\/es\/\" target=\"_blank\">Museo de Los Aromas<\/a> de la vecina localidad de Santa Cruz de la Salceda (Burgos). Los arandinos te esperan con cari\u00f1o&#8230;<\/p>\n<p>&nbsp; <\/p>\n<h4>Art\u00edculos Relacionados:<\/h4>\n<p>&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/este-fin-de-semana-vamonos-aranda-de-duero\/\"><span style=\"color: #000000;\">Este fin de semana, v\u00e1monos a Aranda de Duero!<\/a><br \/>\n&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/tesela-la-nueva-cerveza-artesanal-de-aranda-de-duero\/\"><span style=\"color: #000000;\">Nace Tesela, la nueva cerveza artesanal de Aranda de Duero<\/a><br \/>\n&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/xiii-jornadas-del-lechazo-en-aranda-de-duero\/\"><span style=\"color: #000000;\">XIII Jornadas del Lechazo en Aranda de Duero<\/a><br \/>\n&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/credo-exposcion-de-las-edades-del-hombre-en-arevalo\/\"><span style=\"color: #000000;\">Credo, exposici\u00f3n de las Edades del Hombre en Ar\u00e9valo<\/a><br \/>\n&nbsp; &nbsp; <strong>\u2022 <\/strong><a href=\"http:\/\/destinocastillayleon.es\/index\/visitar-arevalo-durante-la-exposicion-de-las-edades-del-hombre\/\"><span style=\"color: #000000;\">Visitar Ar\u00e9valo durante la Exposici\u00f3n de las Edades del Hombre<\/a><br \/>\n&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya sabemos la fecha de inaguraci\u00f3n de \u00abEucharistia\u00bb, la Exposici\u00f3n de Las Edades del Hombre, la muestra m\u00e1s destacada de arte sacro a nivel internacional<\/p>\n","protected":false},"author":6,"featured_media":12380,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_1150954226_1150954226":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[77,43,68],"tags":[331,1559,2860,1560,1561,3993,2191,1563,2861,2190],"class_list":["post-12373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-y-agenda-de-castilla-y-leon","category-burgos","category-post_inicial","tag-edades-del-hombre","tag-edades-del-hombre-en-aranda-de-duero","tag-espoxiciones-en-aranda-de-duero","tag-eucharistia","tag-exposicion-edades-del-hombre-2014","tag-exposicion-en-aranda-de-duero","tag-las-edades-del-hombre-2014","tag-que-ver-en-aranda-de-duero","tag-que-visitar-en-aranda-el-2014","tag-visitar-aranda-de-duero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Exposici\u00f3n de Las Edades del Hombre<\/title>\n<meta name=\"description\" content=\"Ya sabemos la fecha de inaguraci\u00f3n de &quot;Eucharistia&quot;, la Exposici\u00f3n de Las Edades del Hombre, la muestra m\u00e1s destacada de arte sacro a nivel internacional\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo\" \/>\n<meta property=\"og:description\" content=\"Por fin hemos sabido la fecha en la que &quot;Eucharistia&quot;, la muestra m\u00e1s destacada de arte sacro a nivel nacional e internacional, tendr\u00e1 lugar en Aranda de Duero, Burgos. Las Edades del Hombre ser\u00e1n el 6 de mayo con la presencia de La Infanta Do\u00f1a Elena de Borb\u00f3n y Grecia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Destino Castilla y Le\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DestinoCastillaYLeon\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-29T17:37:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-11-21T10:24:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/Fachada-Iglesia-Santa-Maria-Aranda-de-Duero-Burgos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lola Hernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@destinocyl\" \/>\n<meta name=\"twitter:site\" content=\"@destinocyl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola Hernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/\"},\"author\":{\"name\":\"Lola Hernandez\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/49ffcb7eb307589ba529009335ed7767\"},\"headline\":\"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo\",\"datePublished\":\"2014-03-29T17:37:35+00:00\",\"dateModified\":\"2014-11-21T10:24:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/\"},\"wordCount\":359,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/48e3ba160183c778d2423271900b45c3.png\",\"keywords\":[\"Edades del Hombre\",\"Edades del hombre en Aranda de Duero\",\"espoxiciones en Aranda de Duero\",\"Eucharistia\",\"exposici\u00f3n edades del hombre 2014\",\"exposici\u00f3n en Aranda de Duero\",\"Las Edades del Hombre 2014\",\"qu\u00e9 ver en Aranda de Duero\",\"que visitar en Aranda el 2014\",\"visitar Aranda de Duero\"],\"articleSection\":[\"Actualidad\",\"Burgos\",\"Post_inicial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/\",\"name\":\"Exposici\u00f3n de Las Edades del Hombre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/48e3ba160183c778d2423271900b45c3.png\",\"datePublished\":\"2014-03-29T17:37:35+00:00\",\"dateModified\":\"2014-11-21T10:24:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/49ffcb7eb307589ba529009335ed7767\"},\"description\":\"Ya sabemos la fecha de inaguraci\u00f3n de \\\"Eucharistia\\\", la Exposici\u00f3n de Las Edades del Hombre, la muestra m\u00e1s destacada de arte sacro a nivel internacional\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/48e3ba160183c778d2423271900b45c3.png\",\"contentUrl\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/48e3ba160183c778d2423271900b45c3.png\",\"width\":800,\"height\":509},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#website\",\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/\",\"name\":\"Destino Castilla y Le\u00f3n\",\"description\":\"Medio digital independiente y revista de Castilla y Le\u00f3n dedicado al turismo, gastronom\u00eda y vino de Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/#\\\/schema\\\/person\\\/49ffcb7eb307589ba529009335ed7767\",\"name\":\"Lola Hernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g\",\"caption\":\"Lola Hernandez\"},\"description\":\"Lola Hern\u00e1ndez fue fundadora y directora de www.destinocastillayleon.es Escribiendo sobre turismo, gastronom\u00eda y vino de su tierra de origen, Castilla y Le\u00f3n.\",\"sameAs\":[\"http:\\\/\\\/www.destinoysabor.com\\\/blog\"],\"url\":\"https:\\\/\\\/destinocastillayleon.es\\\/index\\\/author\\\/lola-hernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n de Las Edades del Hombre","description":"Ya sabemos la fecha de inaguraci\u00f3n de \"Eucharistia\", la Exposici\u00f3n de Las Edades del Hombre, la muestra m\u00e1s destacada de arte sacro a nivel internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo","og_description":"Por fin hemos sabido la fecha en la que \"Eucharistia\", la muestra m\u00e1s destacada de arte sacro a nivel nacional e internacional, tendr\u00e1 lugar en Aranda de Duero, Burgos. Las Edades del Hombre ser\u00e1n el 6 de mayo con la presencia de La Infanta Do\u00f1a Elena de Borb\u00f3n y Grecia.","og_url":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/","og_site_name":"Destino Castilla y Le\u00f3n","article_publisher":"https:\/\/www.facebook.com\/DestinoCastillaYLeon\/","article_published_time":"2014-03-29T17:37:35+00:00","article_modified_time":"2014-11-21T10:24:35+00:00","og_image":[{"width":640,"height":415,"url":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/Fachada-Iglesia-Santa-Maria-Aranda-de-Duero-Burgos.png","type":"image\/png"}],"author":"Lola Hernandez","twitter_card":"summary_large_image","twitter_creator":"@destinocyl","twitter_site":"@destinocyl","twitter_misc":{"Escrito por":"Lola Hernandez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#article","isPartOf":{"@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/"},"author":{"name":"Lola Hernandez","@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/49ffcb7eb307589ba529009335ed7767"},"headline":"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo","datePublished":"2014-03-29T17:37:35+00:00","dateModified":"2014-11-21T10:24:35+00:00","mainEntityOfPage":{"@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/"},"wordCount":359,"commentCount":0,"image":{"@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/48e3ba160183c778d2423271900b45c3.png","keywords":["Edades del Hombre","Edades del hombre en Aranda de Duero","espoxiciones en Aranda de Duero","Eucharistia","exposici\u00f3n edades del hombre 2014","exposici\u00f3n en Aranda de Duero","Las Edades del Hombre 2014","qu\u00e9 ver en Aranda de Duero","que visitar en Aranda el 2014","visitar Aranda de Duero"],"articleSection":["Actualidad","Burgos","Post_inicial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/","url":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/","name":"Exposici\u00f3n de Las Edades del Hombre","isPartOf":{"@id":"https:\/\/destinocastillayleon.es\/index\/#website"},"primaryImageOfPage":{"@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#primaryimage"},"image":{"@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/48e3ba160183c778d2423271900b45c3.png","datePublished":"2014-03-29T17:37:35+00:00","dateModified":"2014-11-21T10:24:35+00:00","author":{"@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/49ffcb7eb307589ba529009335ed7767"},"description":"Ya sabemos la fecha de inaguraci\u00f3n de \"Eucharistia\", la Exposici\u00f3n de Las Edades del Hombre, la muestra m\u00e1s destacada de arte sacro a nivel internacional","breadcrumb":{"@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#primaryimage","url":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/48e3ba160183c778d2423271900b45c3.png","contentUrl":"https:\/\/destinocastillayleon.es\/index\/wp-content\/uploads\/2014\/03\/48e3ba160183c778d2423271900b45c3.png","width":800,"height":509},{"@type":"BreadcrumbList","@id":"https:\/\/destinocastillayleon.es\/index\/la-nueva-exposicion-de-las-edades-del-hombre-se-inaugurara-el-6-de-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/destinocastillayleon.es\/index\/"},{"@type":"ListItem","position":2,"name":"La nueva exposici\u00f3n de Las Edades del Hombre se inaugurar\u00e1 el 6 de mayo"}]},{"@type":"WebSite","@id":"https:\/\/destinocastillayleon.es\/index\/#website","url":"https:\/\/destinocastillayleon.es\/index\/","name":"Destino Castilla y Le\u00f3n","description":"Medio digital independiente y revista de Castilla y Le\u00f3n dedicado al turismo, gastronom\u00eda y vino de Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/destinocastillayleon.es\/index\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/destinocastillayleon.es\/index\/#\/schema\/person\/49ffcb7eb307589ba529009335ed7767","name":"Lola Hernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ead65e55ad0522fba484acfe2842bf78b2f7c727df41d76fed78a85519da34?s=96&d=mm&r=g","caption":"Lola Hernandez"},"description":"Lola Hern\u00e1ndez fue fundadora y directora de www.destinocastillayleon.es Escribiendo sobre turismo, gastronom\u00eda y vino de su tierra de origen, Castilla y Le\u00f3n.","sameAs":["http:\/\/www.destinoysabor.com\/blog"],"url":"https:\/\/destinocastillayleon.es\/index\/author\/lola-hernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/12373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/comments?post=12373"}],"version-history":[{"count":9,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/12373\/revisions"}],"predecessor-version":[{"id":17069,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/posts\/12373\/revisions\/17069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/media\/12380"}],"wp:attachment":[{"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/media?parent=12373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/categories?post=12373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/destinocastillayleon.es\/index\/wp-json\/wp\/v2\/tags?post=12373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}